{"id":2520,"date":"2018-08-28T18:32:03","date_gmt":"2018-08-28T16:32:03","guid":{"rendered":"http:\/\/www.senka.fr\/blog\/?p=2520"},"modified":"2018-10-09T12:36:04","modified_gmt":"2018-10-09T10:36:04","slug":"machu-picchu","status":"publish","type":"post","link":"https:\/\/www.senka.fr\/blog\/machu-picchu\/","title":{"rendered":"Machu Picchu"},"content":{"rendered":"\n<p>En ce jour f\u00e9ri\u00e9 p\u00e9ruvien, la Santa Rosa de Lima, nous revenons tout juste d\u2019un tour de trois jours dans la r\u00e9gion d\u2019Urubamba.<br\/>Lundi, nous sommes partis de bonne heure de Cusco pour faire une route de 6 heures. Arriv\u00e9s \u00e0 Hydroelectrica (centrale hydro-\u00e9lectrique), une marche initialement pr\u00e9vue de deux heures (12 km) nous attendait pour contourner le mont Picchu en suivant le rail. Partis \u00e0 14h, nous sommes enfin arriv\u00e9s \u00e0 18h sous une pluie diluvienne\u00a0! Tout tremp\u00e9s, nous demandons un mini s\u00e8che-cheveux pour tenter de mettre nos chaussures \u00e0 sec. Pari r\u00e9ussi.<br\/>Mardi, le grand jour est arriv\u00e9, la visite de l\u2019une des 7 merveilles du monde moderne, le <strong>Machu Picchu<\/strong>.<br\/>Une mont\u00e9e en bus et, grandiose, le site \u00e9clair\u00e9 par un splendide rayon de soleil nous laissait bouche b\u00e9e. Surpris par ce lieu perch\u00e9 en haut de Huayna Picchu qui est tr\u00e8s bien entretenu. Il a \u00e9t\u00e9 d\u00e9laiss\u00e9 par les Incas quand ils ont appris que les espagnols avaient conquis Cusco vers l&#8217;an 1540.<br\/>D\u00e9couvert seulement en 1911 par un arch\u00e9ologue am\u00e9ricain, la ville aux 1200 habitants a \u00e9t\u00e9 construite aux alentours de 1435. Surprenant, pendant pr\u00e8s de trois si\u00e8cles, les ruines ne sont pas trop abim\u00e9es par le temps.<br\/>De retour \u00e0 Aguas Calientes par une descente de deux heures \u00e0 pied, nous avons pris le train pour Ollantaytambo, un autre village Incas.<br\/>Pour le dernier jour de ce tour, mercredi, Luis (un chauffeur de taxi) nous a guid\u00e9s pour visiter la vall\u00e9e des Incas (Moray, Sal de Maras et Chinchero). Une vraie journ\u00e9e de d\u00e9couverte et d\u2019apprentissage de la culture locale (labo agronome, village autochtone, marais de sel). A chaque \u00e9tape, Luis parlait dans Google Traductor pour transcrire en fran\u00e7ais. A la fin du parcours, il nous a emmen\u00e9s dans un march\u00e9 artisanal o\u00f9 l&#8217;on nous a expliqu\u00e9 les \u00e9tapes de fabrication de tissu (de la tonte de mouton au tissage des habits en passant par la colorisation). Nous y avons fait la rencontre avec un fille sourde, muette et autiste, elle s&#8217;appelle Roxana.<br\/><\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2519\" data-permalink=\"https:\/\/www.senka.fr\/blog\/le-perurail\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Le PeruRail&quot;,&quot;created_timestamp&quot;:&quot;1535381612&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;32&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;Le PeruRail&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Le PeruRail\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Le PeruRail&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?resize=474%2C314\" alt=\"\" data-id=\"2519\" data-link=\"http:\/\/www.senka.fr\/blog\/le-perurail\/\" class=\"wp-image-2519\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-145332.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Le PeruRail<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2521\" data-permalink=\"https:\/\/www.senka.fr\/blog\/la-marche-sur-le-rail\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;La marche sur le rail&quot;,&quot;created_timestamp&quot;:&quot;1535382517&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;22&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;La marche sur le rail&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"La marche sur le rail\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;La marche sur le rail&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?resize=474%2C314\" alt=\"\" data-id=\"2521\" data-link=\"http:\/\/www.senka.fr\/blog\/la-marche-sur-le-rail\/\" class=\"wp-image-2521\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-150837.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>La marche sur le rail<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2522\" data-permalink=\"https:\/\/www.senka.fr\/blog\/en-route-vers-aguas-calientes\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;En route vers Aguas Calientes&quot;,&quot;created_timestamp&quot;:&quot;1535384085&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;105&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;En route vers Aguas Calientes&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"En route vers Aguas Calientes\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;En route vers Aguas Calientes&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?resize=474%2C314\" alt=\"\" data-id=\"2522\" data-link=\"http:\/\/www.senka.fr\/blog\/en-route-vers-aguas-calientes\/\" class=\"wp-image-2522\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-153445.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>En route vers Aguas Calientes<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2523\" data-permalink=\"https:\/\/www.senka.fr\/blog\/belle-vue-sur-le-rio-urubamba\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Belle vue sur le Rio Urubamba&quot;,&quot;created_timestamp&quot;:&quot;1535385080&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;Belle vue sur le Rio Urubamba&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Belle vue sur le Rio Urubamba\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Belle vue sur le Rio Urubamba&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?resize=474%2C314\" alt=\"\" data-id=\"2523\" data-link=\"http:\/\/www.senka.fr\/blog\/belle-vue-sur-le-rio-urubamba\/\" class=\"wp-image-2523\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180827-155121.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Belle vue sur le Rio Urubamba<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2524\" data-permalink=\"https:\/\/www.senka.fr\/blog\/macchu-pichu\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Macchu Pichu&quot;,&quot;created_timestamp&quot;:&quot;1535441586&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;Macchu Pichu&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Machu Picchu\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Machu Picchu&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?resize=474%2C314\" alt=\"\" data-id=\"2524\" data-link=\"http:\/\/www.senka.fr\/blog\/macchu-pichu\/\" class=\"wp-image-2524\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073306.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Machu Picchu<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2525\" data-permalink=\"https:\/\/www.senka.fr\/blog\/la-pose-en-famille\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;La pose en famille&quot;,&quot;created_timestamp&quot;:&quot;1535441924&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;La pose en famille&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"La pose en famille\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;La pose en famille&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?resize=474%2C314\" alt=\"\" data-id=\"2525\" data-link=\"http:\/\/www.senka.fr\/blog\/la-pose-en-famille\/\" class=\"wp-image-2525\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-073844.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>La pose en famille<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2526\" data-permalink=\"https:\/\/www.senka.fr\/blog\/une-charniere-de-porte\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Une charni\\u00e8re de porte&quot;,&quot;created_timestamp&quot;:&quot;1535445958&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;Une charni\\u00e8re de porte&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Une charni\u00e8re de porte\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Une charni\u00e8re de porte&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?resize=474%2C314\" alt=\"\" data-id=\"2526\" data-link=\"http:\/\/www.senka.fr\/blog\/une-charniere-de-porte\/\" class=\"wp-image-2526\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084558.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Une charni\u00e8re de porte<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2527\" data-permalink=\"https:\/\/www.senka.fr\/blog\/vue-sur-le-rio-urubamba\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Vue sur le Rio Urubamba&quot;,&quot;created_timestamp&quot;:&quot;1535446114&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Vue sur le Rio Urubamba&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vue sur le Rio Urubamba\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Vue sur le Rio Urubamba&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?resize=474%2C314\" alt=\"\" data-id=\"2527\" data-link=\"http:\/\/www.senka.fr\/blog\/vue-sur-le-rio-urubamba\/\" class=\"wp-image-2527\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-084834.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Vue sur le Rio Urubamba<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2528\" data-permalink=\"https:\/\/www.senka.fr\/blog\/temple-des-trois-fenetres\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Temple des \\&quot;Trois Fen\\u00eatres\\&quot;&quot;,&quot;created_timestamp&quot;:&quot;1535447066&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;Temple des \\&quot;Trois Fen\\u00eatres\\&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Temple des &#8220;Trois Fen\u00eatres&#8221;\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Temple des &#8220;Trois Fen\u00eatres&#8221;&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?resize=474%2C314\" alt=\"\" data-id=\"2528\" data-link=\"http:\/\/www.senka.fr\/blog\/temple-des-trois-fenetres\/\" class=\"wp-image-2528\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-090426.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Temple des &#8220;Trois Fen\u00eatres&#8221;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2529\" data-permalink=\"https:\/\/www.senka.fr\/blog\/groupe-des-trois-portes\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.3&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Groupe des Trois Portes&quot;,&quot;created_timestamp&quot;:&quot;1535448680&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;62&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;Groupe des Trois Portes&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Groupe des Trois Portes\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Groupe des Trois Portes&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?resize=474%2C314\" alt=\"\" data-id=\"2529\" data-link=\"http:\/\/www.senka.fr\/blog\/groupe-des-trois-portes\/\" class=\"wp-image-2529\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-093120.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Groupe des Trois Portes<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2530\" data-permalink=\"https:\/\/www.senka.fr\/blog\/un-petit-garcon-avec-son-jouet\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Un petit gar\\u00e7on avec son jouet&quot;,&quot;created_timestamp&quot;:&quot;1535457214&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;Un petit gar\\u00e7on avec son jouet&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Un petit gar\u00e7on avec son jouet\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Un petit gar\u00e7on avec son jouet&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?resize=474%2C314\" alt=\"\" data-id=\"2530\" data-link=\"http:\/\/www.senka.fr\/blog\/un-petit-garcon-avec-son-jouet\/\" class=\"wp-image-2530\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115334.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Un petit gar\u00e7on avec son jouet<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2532\" data-permalink=\"https:\/\/www.senka.fr\/blog\/aguas-calientes\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Aguas Calientes&quot;,&quot;created_timestamp&quot;:&quot;1535457320&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Aguas Calientes&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Aguas Calientes\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Aguas Calientes&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?resize=474%2C314\" alt=\"\" data-id=\"2532\" data-link=\"http:\/\/www.senka.fr\/blog\/aguas-calientes\/\" class=\"wp-image-2532\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115520.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Aguas Calientes<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2533\" data-permalink=\"https:\/\/www.senka.fr\/blog\/sur-la-place-manco-capac-daguas-calientes\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Sur la place Manco Capac d&#039;Aguas Calientes&quot;,&quot;created_timestamp&quot;:&quot;1535457419&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;25&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Sur la place Manco Capac d&#039;Aguas Calientes&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Sur la place Manco Capac d&#8217;Aguas Calientes\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Sur la place Manco Capac d&#8217;Aguas Calientes&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?resize=474%2C314\" alt=\"\" data-id=\"2533\" data-link=\"http:\/\/www.senka.fr\/blog\/sur-la-place-manco-capac-daguas-calientes\/\" class=\"wp-image-2533\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-115659.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Sur la place Manco Capac d&#8217;Aguas Calientes<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2535\" data-permalink=\"https:\/\/www.senka.fr\/blog\/en-route-vers-ollantaytambo\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;En route vers Ollantaytambo&quot;,&quot;created_timestamp&quot;:&quot;1535463079&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;En route vers Ollantaytambo&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"En route vers Ollantaytambo\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;En route vers Ollantaytambo&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?resize=474%2C314\" alt=\"\" data-id=\"2535\" data-link=\"http:\/\/www.senka.fr\/blog\/en-route-vers-ollantaytambo\/\" class=\"wp-image-2535\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-133119.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>En route vers Ollantaytambo<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2536\" data-permalink=\"https:\/\/www.senka.fr\/blog\/sur-le-quai-dollantaytambo\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Sur le quai d&#039;Ollantaytambo&quot;,&quot;created_timestamp&quot;:&quot;1535469024&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Sur le quai d&#039;Ollantaytambo&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Sur le quai d&#8217;Ollantaytambo\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Sur le quai d&#8217;Ollantaytambo&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?resize=474%2C314\" alt=\"\" data-id=\"2536\" data-link=\"http:\/\/www.senka.fr\/blog\/sur-le-quai-dollantaytambo\/\" class=\"wp-image-2536\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-151024.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Sur le quai d&#8217;Ollantaytambo<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2537\" data-permalink=\"https:\/\/www.senka.fr\/blog\/les-enfants-dollantaytambo\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.2&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Les enfants d&#039;Ollantaytambo&quot;,&quot;created_timestamp&quot;:&quot;1535470193&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;34&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;Les enfants d&#039;Ollantaytambo&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Les enfants d&#8217;Ollantaytambo\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Les enfants d&#8217;Ollantaytambo&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?resize=474%2C314\" alt=\"\" data-id=\"2537\" data-link=\"http:\/\/www.senka.fr\/blog\/les-enfants-dollantaytambo\/\" class=\"wp-image-2537\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-152953.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Les enfants d&#8217;Ollantaytambo<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2538\" data-permalink=\"https:\/\/www.senka.fr\/blog\/un-moment-de-repit\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Un moment de r\\u00e9pit...&quot;,&quot;created_timestamp&quot;:&quot;1535470520&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;105&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Un moment de r\\u00e9pit...&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Un moment de r\u00e9pit&#8230;\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Un moment de r\u00e9pit&#8230;&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?resize=474%2C314\" alt=\"\" data-id=\"2538\" data-link=\"http:\/\/www.senka.fr\/blog\/un-moment-de-repit\/\" class=\"wp-image-2538\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-153520.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Un moment de r\u00e9pit&#8230;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2546\" data-permalink=\"https:\/\/www.senka.fr\/blog\/de-leau-tres-sale-venu-de-la-montagne\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;de l&#039;eau tr\\u00e8s sal\\u00e9 venu de la montagne&quot;,&quot;created_timestamp&quot;:&quot;1535556827&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;105&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;de l&#039;eau tr\\u00e8s sal\\u00e9 venu de la montagne&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"de l&#8217;eau tr\u00e8s sal\u00e9 venu de la montagne\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;de l&#8217;eau tr\u00e8s sal\u00e9 venu de la montagne&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?resize=474%2C314\" alt=\"\" data-id=\"2546\" data-link=\"http:\/\/www.senka.fr\/blog\/de-leau-tres-sale-venu-de-la-montagne\/\" class=\"wp-image-2546\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-153347.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>de l&#8217;eau tr\u00e8s sal\u00e9 venu de la montagne<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2539\" data-permalink=\"https:\/\/www.senka.fr\/blog\/mmmmhhh-les-papas\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Mmmmhhh, les \\&quot;papas\\&quot;&quot;,&quot;created_timestamp&quot;:&quot;1535471023&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;220&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Mmmmhhh, les \\&quot;papas\\&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mmmmhhh, les &#8220;papas&#8221;\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mmmmhhh, les &#8220;papas&#8221;&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?resize=474%2C314\" alt=\"\" data-id=\"2539\" data-link=\"http:\/\/www.senka.fr\/blog\/mmmmhhh-les-papas\/\" class=\"wp-image-2539\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-154343.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Mmmmhhh, les &#8220;papas&#8221;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2540\" data-permalink=\"https:\/\/www.senka.fr\/blog\/petit-cours-dhistoire\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Petit cours d&#039;Histoire&quot;,&quot;created_timestamp&quot;:&quot;1535541432&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;34&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;Petit cours d&#039;Histoire&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Petit cours d&#8217;Histoire\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Petit cours d&#8217;Histoire&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?resize=474%2C314\" alt=\"\" data-id=\"2540\" data-link=\"http:\/\/www.senka.fr\/blog\/petit-cours-dhistoire\/\" class=\"wp-image-2540\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-111712.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Petit cours d&#8217;Histoire<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2541\" data-permalink=\"https:\/\/www.senka.fr\/blog\/vue-sur-la-chaine-de-montagne-veronica\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;14&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Vue sur la chaine de montagne \\&quot;Veronica\\&quot;&quot;,&quot;created_timestamp&quot;:&quot;1535551129&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;Vue sur la chaine de montagne \\&quot;Veronica\\&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vue sur la chaine de montagne &#8220;Veronica&#8221;\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Vue sur la chaine de montagne &#8220;Veronica&#8221;&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?resize=474%2C314\" alt=\"\" data-id=\"2541\" data-link=\"http:\/\/www.senka.fr\/blog\/vue-sur-la-chaine-de-montagne-veronica\/\" class=\"wp-image-2541\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-135849.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Vue sur la chaine de montagne &#8220;Veronica&#8221;<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2542\" data-permalink=\"https:\/\/www.senka.fr\/blog\/le-labo-agronome-de-moray\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;13&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Le labo agronome de Moray&quot;,&quot;created_timestamp&quot;:&quot;1535552466&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.0015625&quot;,&quot;title&quot;:&quot;Le labo agronome de Moray&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Le labo agronome de Moray\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Le labo agronome de Moray&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?resize=474%2C314\" alt=\"\" data-id=\"2542\" data-link=\"http:\/\/www.senka.fr\/blog\/le-labo-agronome-de-moray\/\" class=\"wp-image-2542\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-142106.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Le labo agronome de Moray<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2543\" data-permalink=\"https:\/\/www.senka.fr\/blog\/sur-la-place-de-maras\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;6.3&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Sur la place de Maras&quot;,&quot;created_timestamp&quot;:&quot;1535554060&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;58&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.0015625&quot;,&quot;title&quot;:&quot;Sur la place de Maras&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Sur la place de Maras\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Sur la place de Maras&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?resize=474%2C314\" alt=\"\" data-id=\"2543\" data-link=\"http:\/\/www.senka.fr\/blog\/sur-la-place-de-maras\/\" class=\"wp-image-2543\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-144740.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Sur la place de Maras<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2544\" data-permalink=\"https:\/\/www.senka.fr\/blog\/boisson-a-base-de-mais-fermente\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;6.3&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Boisson \\u00e0 base de ma\\u00efs ferment\\u00e9&quot;,&quot;created_timestamp&quot;:&quot;1535554661&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;Boisson \\u00e0 base de ma\\u00efs ferment\\u00e9&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Boisson \u00e0 base de ma\u00efs ferment\u00e9\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Boisson \u00e0 base de ma\u00efs ferment\u00e9&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?resize=474%2C314\" alt=\"\" data-id=\"2544\" data-link=\"http:\/\/www.senka.fr\/blog\/boisson-a-base-de-mais-fermente\/\" class=\"wp-image-2544\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-145741.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Boisson \u00e0 base de ma\u00efs ferment\u00e9<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2545\" data-permalink=\"https:\/\/www.senka.fr\/blog\/le-marais-de-sel-a-maras\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Le marais de sel \\u00e0 Maras&quot;,&quot;created_timestamp&quot;:&quot;1535556035&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;105&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;Le marais de sel \\u00e0 Maras&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Le marais de sel \u00e0 Maras\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Le marais de sel \u00e0 Maras&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?resize=474%2C314\" alt=\"\" data-id=\"2545\" data-link=\"http:\/\/www.senka.fr\/blog\/le-marais-de-sel-a-maras\/\" class=\"wp-image-2545\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-152035.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Le marais de sel \u00e0 Maras<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2547\" data-permalink=\"https:\/\/www.senka.fr\/blog\/sal-de-maras\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Sal de Maras&quot;,&quot;created_timestamp&quot;:&quot;1535557500&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;85&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;Sal de Maras&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Sal de Maras\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Sal de Maras&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?resize=474%2C314\" alt=\"\" data-id=\"2547\" data-link=\"http:\/\/www.senka.fr\/blog\/sal-de-maras\/\" class=\"wp-image-2547\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-154500.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Sal de Maras<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2548\" data-permalink=\"https:\/\/www.senka.fr\/blog\/la-virgen-asunta-de-tiobamba\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;La Virgen Asunta de Tiobamba&quot;,&quot;created_timestamp&quot;:&quot;1535559117&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;42&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;La Virgen Asunta de Tiobamba&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"La Virgen Asunta de Tiobamba\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;La Virgen Asunta de Tiobamba&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?resize=474%2C314\" alt=\"\" data-id=\"2548\" data-link=\"http:\/\/www.senka.fr\/blog\/la-virgen-asunta-de-tiobamba\/\" class=\"wp-image-2548\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-161157.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>La Virgen Asunta de Tiobamba<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2549\" data-permalink=\"https:\/\/www.senka.fr\/blog\/habitant-de-chinchero\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.3&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Habitant de Chinchero&quot;,&quot;created_timestamp&quot;:&quot;1535561334&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;75&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;Habitant de Chinchero&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Habitant de Chinchero\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Habitant de Chinchero&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?resize=474%2C314\" alt=\"\" data-id=\"2549\" data-link=\"http:\/\/www.senka.fr\/blog\/habitant-de-chinchero\/\" class=\"wp-image-2549\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-164854.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Habitant de Chinchero<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2550\" data-permalink=\"https:\/\/www.senka.fr\/blog\/vue-sur-chinchero\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;14&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Vue sur Chinchero&quot;,&quot;created_timestamp&quot;:&quot;1535562358&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;Vue sur Chinchero&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vue sur Chinchero\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Vue sur Chinchero&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?resize=474%2C314\" alt=\"\" data-id=\"2550\" data-link=\"http:\/\/www.senka.fr\/blog\/vue-sur-chinchero\/\" class=\"wp-image-2550\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-170558.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Vue sur Chinchero<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2551\" data-permalink=\"https:\/\/www.senka.fr\/blog\/pose-au-coucher-du-soleil-a-chinchero\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Pose au coucher du soleil \\u00e0 Chinchero&quot;,&quot;created_timestamp&quot;:&quot;1535562604&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;42&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;Pose au coucher du soleil \\u00e0 Chinchero&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Pose au coucher du soleil \u00e0 Chinchero\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Pose au coucher du soleil \u00e0 Chinchero&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?resize=474%2C314\" alt=\"\" data-id=\"2551\" data-link=\"http:\/\/www.senka.fr\/blog\/pose-au-coucher-du-soleil-a-chinchero\/\" class=\"wp-image-2551\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171004.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Pose au coucher du soleil \u00e0 Chinchero<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2553\" data-permalink=\"https:\/\/www.senka.fr\/blog\/une-fille-avec-son-cerf-volant\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Une fille avec son cerf volant&quot;,&quot;created_timestamp&quot;:&quot;1535563053&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;52&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;Une fille avec son cerf volant&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Une fille avec son cerf volant\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Une fille avec son cerf volant&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?resize=474%2C314\" alt=\"\" data-id=\"2553\" data-link=\"http:\/\/www.senka.fr\/blog\/une-fille-avec-son-cerf-volant\/\" class=\"wp-image-2553\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-171733.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Une fille avec son cerf volant<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2554\" data-permalink=\"https:\/\/www.senka.fr\/blog\/cantuta-fleur-de-linca-et-fleur-national-du-perou\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Cantuta, fleur de l&#039;inca et fleur national du P\\u00e9rou&quot;,&quot;created_timestamp&quot;:&quot;1535563483&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;105&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;Cantuta, fleur de l&#039;inca et fleur national du P\\u00e9rou&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Cantuta, fleur de l&#8217;inca et fleur national du P\u00e9rou\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Cantuta, fleur de l&#8217;inca et fleur national du P\u00e9rou&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?resize=474%2C314\" alt=\"\" data-id=\"2554\" data-link=\"http:\/\/www.senka.fr\/blog\/cantuta-fleur-de-linca-et-fleur-national-du-perou\/\" class=\"wp-image-2554\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-172443.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Cantuta, fleur de l&#8217;inca et fleur national du P\u00e9rou<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"314\" data-attachment-id=\"2555\" data-permalink=\"https:\/\/www.senka.fr\/blog\/colorisation-de-tissu\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?fit=1087%2C720&amp;ssl=1\" data-orig-size=\"1087,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;Senka&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;Colorisation de tissu&quot;,&quot;created_timestamp&quot;:&quot;1535565252&quot;,&quot;copyright&quot;:&quot;Senka&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;1000&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;Colorisation de tissu&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Colorisation de tissu\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Colorisation de tissu&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?fit=512%2C339&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?fit=474%2C314&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?resize=474%2C314\" alt=\"\" data-id=\"2555\" data-link=\"http:\/\/www.senka.fr\/blog\/colorisation-de-tissu\/\" class=\"wp-image-2555\" srcset=\"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?w=1087&amp;ssl=1 1087w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?resize=512%2C339&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?resize=1024%2C678&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180829-175412.jpg?w=948&amp;ssl=1 948w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><figcaption>Colorisation de tissu<\/figcaption><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En ce jour f\u00e9ri\u00e9 p\u00e9ruvien, la Santa Rosa de Lima, nous revenons tout juste d\u2019un tour de trois jours dans la r\u00e9gion d\u2019Urubamba.Lundi, nous sommes partis de bonne heure de Cusco pour faire une route de 6 heures. Arriv\u00e9s \u00e0 Hydroelectrica (centrale hydro-\u00e9lectrique), une marche initialement pr\u00e9vue de deux heures (12 km) nous attendait pour &hellip; <a href=\"https:\/\/www.senka.fr\/blog\/machu-picchu\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Machu Picchu<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,7],"tags":[],"class_list":["post-2520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amerique-du-sud","category-perou"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.senka.fr\/blog\/wp-content\/uploads\/2018\/08\/20180828-074014.jpg?fit=1040%2C208&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8IlF9-EE","_links":{"self":[{"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/posts\/2520"}],"collection":[{"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/comments?post=2520"}],"version-history":[{"count":6,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/posts\/2520\/revisions"}],"predecessor-version":[{"id":2560,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/posts\/2520\/revisions\/2560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/media\/2558"}],"wp:attachment":[{"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/media?parent=2520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/categories?post=2520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.senka.fr\/blog\/wp-json\/wp\/v2\/tags?post=2520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}